{"id":90194,"date":"2024-05-27T10:51:30","date_gmt":"2024-05-27T14:51:30","guid":{"rendered":"https:\/\/stage.rdvcanada.ca\/?p=90194"},"modified":"2024-06-21T16:10:21","modified_gmt":"2024-06-21T20:10:21","slug":"rdv-canada-docs-2024","status":"publish","type":"post","link":"https:\/\/stage.rdvcanada.ca\/fr\/succes\/rdv-canada-docs-2024\/","title":{"rendered":"RDVCANADA | Docs 2024"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"90194\" class=\"elementor elementor-90194 elementor-90137\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9be6fa3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9be6fa3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-34d0e43\" data-id=\"34d0e43\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e86b8e3 elementor-widget elementor-widget-heading\" data-id=\"e86b8e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Sunny Side of the Doc, les voici!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b9d81b elementor-widget elementor-widget-heading\" data-id=\"1b9d81b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Dans le cadre de notre initiative de mentorat RDVCANADA, notre deuxi\u00e8me cohorte de productrices et de producteurs de documentaires est pr\u00eate \u00e0 s\u2019attaquer au march\u00e9 mondial pour trouver leurs prochains partenaires d\u2019affaires internationaux.  <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43959ae elementor-widget elementor-widget-text-editor\" data-id=\"43959ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Arm\u00e9s de leurs projets documentaires en d\u00e9veloppement, les sept productrices et producteurs s\u00e9lectionn\u00e9s pour <strong>RDVCANADA | Docs 2024<\/strong> se pr\u00e9parent \u00e0 pr\u00e9senter leur projet au Sunny Side of the Doc du 24 au 27 juin 2024 \u00e0 La Rochelle, en France.<\/p><p>Dans le cadre de ce programme professionnel unique men\u00e9 par T\u00e9l\u00e9film Canada, en partenariat avec le <a href=\"https:\/\/bso-ben.ca\/fr\/accueil\/\">Bureau de l&#8217;\u00e9cran des Noir<\/a>, le <a href=\"https:\/\/iso-bea.ca\/fr\/\">Bureau de l&#8217;\u00e9cran autochtone<\/a>, <a href=\"https:\/\/creativebc.com\/\">Creative BC<\/a>, <a href=\"https:\/\/www.ontariocreates.ca\/fr\/\">Ontario Cr\u00e9atif<\/a> et la <a href=\"https:\/\/sodec.gouv.qc.ca\/\">SODEC<\/a>, les productrices et producteurs ont particip\u00e9 \u00e0 six semaines intensives de mentorat et de formation personnalis\u00e9s (l\u2019accent \u00e9tant mis sur la coproduction internationale et la distribution, de m\u00eame que sur la pr\u00e9sentation des projets) et sont maintenant pr\u00eats \u00e0 promouvoir leurs projets devant leurs futurs partenaires internationaux.<\/p><p>Si vous travaillez en distribution internationale, en ventes, en t\u00e9l\u00e9diffusion ou si vous \u00eates \u00e0 la recherche d\u2019un coproducteur et que vous pr\u00e9voyez de participer au Sunny Side of the Doc, c\u2019est l\u2019occasion pour vous de d\u00e9couvrir en primeur ces histoires vou\u00e9es au succ\u00e8s et de b\u00e2tir de solides relations d\u2019affaires avec des productrices et des producteurs de documentaires canadiens d\u2019exp\u00e9rience et dont l\u2019offre va des s\u00e9ries t\u00e9l\u00e9vis\u00e9es aux longs m\u00e9trages.<\/p><p>Outre une s\u00e9rie d\u2019activit\u00e9s de r\u00e9seautage (sur invitation seulement), vous pourrez rencontrer les membres de la cohorte de RDVCANADA I Docs toute la semaine au<strong> Pavillon du Canada &#8211; Stand B23<\/strong>!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1403a6a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1403a6a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3138091\" data-id=\"3138091\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-55ac1c7 elementor-widget elementor-widget-heading\" data-id=\"55ac1c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">C\u2019est avec beaucoup de fiert\u00e9 que nous d\u00e9voilons les productrices, les producteurs et les projets de la cohorte RDVCANADA | Docs 2024!<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eff13ff elementor-widget elementor-widget-spacer\" data-id=\"eff13ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a938fed elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a938fed\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-2edeedc\" data-id=\"2edeedc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0936c6d elementor-widget elementor-widget-heading\" data-id=\"0936c6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">On Distant Shores \u2013 S\u00e9rie<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b839a87 elementor-widget elementor-widget-text-editor\" data-id=\"b839a87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/stage.rdvcanada.ca\/fr\/creer-avec-le-canada\/trouver-des-partenaires-creatifs\/producteurs\/barbara-hager\/\" target=\"_blank\" rel=\"noopener\"><strong>Barbara Todd Hager<\/strong><\/a><strong>, Acimow Media Ltd. (Colombie-Britannique) <br \/><\/strong><\/p><p><em>On Distant Shores<\/em> nous fait d\u00e9couvrir les voyages extraordinaires effectu\u00e9s par des peuples autochtones de l\u2019Am\u00e9rique du Nord et du Sud dans des pays europ\u00e9ens, changeant tout ce que nous savons sur l\u2019histoire des interactions entre Europ\u00e9ens et Autochtones apr\u00e8s 1492.<\/p><p><em>La participation de la productrice est soutenue par le Bureau de l\u2019\u00e9cran autochtone.<\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-03973c0\" data-id=\"03973c0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f73d44 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"3f73d44\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrousel d\u2019images\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 2\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/stage.rdvcanada.ca\/wp-content\/uploads\/2024\/05\/Acimow-media-Barbara-Hager-2024.png\" alt=\"Acimow media - Barbara Hager-2024\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 2\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/stage.rdvcanada.ca\/wp-content\/uploads\/2018\/01\/ISO-Logo-FR.png\" alt=\"ISO - Logo - FR\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6186140 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6186140\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-f134f69\" data-id=\"f134f69\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8923563 elementor-widget elementor-widget-heading\" data-id=\"8923563\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Seagulls Over the Airwaves \u2013  Long m\u00e9trage<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2eb6c13 elementor-widget elementor-widget-text-editor\" data-id=\"2eb6c13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Leon Lee, <a href=\"https:\/\/stage.rdvcanada.ca\/fr\/creer-avec-le-canada\/trouver-des-partenaires-creatifs\/compagnies\/flying-cloud-productions\/\">Flying Cloud Productions<\/a> (Colombie-Britannique)<br \/><\/strong><\/p><p>Nom de code: Projet Seagull. Un audacieux r\u00e9seau de gens ordinaires d\u00e9fie la censure de point de la Chine avec un ing\u00e9nieux piratage de la radio \u00e0 ondes courtes, risquant tout pour diffuser des informations non censur\u00e9es et d\u00e9clencher une r\u00e9volution de l&#8217;information.<\/p><p><em>La participation du producteur est soutenue par Creative BC.<\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4077fd9\" data-id=\"4077fd9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c86a01 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"4c86a01\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrousel d\u2019images\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 2\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/stage.rdvcanada.ca\/wp-content\/uploads\/2018\/01\/Flying-Cloud-Leon-Lee.png\" alt=\"Flying Cloud - Leon Lee\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 2\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/stage.rdvcanada.ca\/wp-content\/uploads\/2018\/01\/Creative-BC-Meet-the-Docs-Logo-1.png\" alt=\"Creative BC - Meet the Docs Logo\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9129f66 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9129f66\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-0516eca\" data-id=\"0516eca\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-52eddb8 elementor-widget elementor-widget-heading\" data-id=\"52eddb8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Uncomfortable Truths \u2013  Long m\u00e9trage<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dda7051 elementor-widget elementor-widget-text-editor\" data-id=\"dda7051\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/stage.rdvcanada.ca\/fr\/creer-avec-le-canada\/trouver-des-partenaires-creatifs\/producteurs\/eric-ruel\/\"><strong>Eric Ruel<\/strong><\/a><strong>, La Ruelle Films (Qu\u00e9bec)<\/strong><\/p><p>Dans un petit village nich\u00e9 dans les montagnes enneig\u00e9es des Laurentides, les habitants sont boulevers\u00e9s par l&#8217;apparition myst\u00e9rieuse de triangles noirs dans le ciel. La plupart des t\u00e9moins croient \u00e0 une origine non humaine. Alors que la qu\u00eate de r\u00e9ponses s&#8217;amorce, une v\u00e9ritable r\u00e9volution scientifique se r\u00e9v\u00e8le.<\/p><p><em>La participation du producteur est soutenue par Qu\u00e9bec cr\u00e9atif, Sodec.<\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7c87e9e\" data-id=\"7c87e9e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12a2776 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"12a2776\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrousel d\u2019images\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 2\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/stage.rdvcanada.ca\/wp-content\/uploads\/2018\/01\/La-Ruelle-Films-Eric-Ruel.png\" alt=\"La Ruelle Films - Eric Ruel\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 2\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/stage.rdvcanada.ca\/wp-content\/uploads\/2018\/01\/Quebec-Creates-FR-Meet-the-Docs-2024.png\" alt=\"Quebec Creates - FR - Meet the Docs 2024\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4270e68 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4270e68\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-e332522\" data-id=\"e332522\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bb08583 elementor-widget elementor-widget-heading\" data-id=\"bb08583\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">On Bass  \u2013  Long m\u00e9trage<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5858280 elementor-widget elementor-widget-text-editor\" data-id=\"5858280\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/stage.rdvcanada.ca\/fr\/creer-avec-le-canada\/trouver-des-partenaires-creatifs\/producteurs\/james-weyman\/\"><strong>James Weyman<\/strong><\/a><strong>, Markham Street Films Inc. (Ontario)<\/strong><\/p><p>On Bass est une c\u00e9l\u00e9bration de la guitare basse \u00e9lectrique et des bassistes qui l\u2019ont jou\u00e9 pour r\u00e9volutionner la musique populaire.<\/p><p><em>La participation du producteur est soutenue par Ontario Cr\u00e9atif.<\/em> <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-fed6143\" data-id=\"fed6143\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e45d268 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"e45d268\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrousel d\u2019images\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 2\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/stage.rdvcanada.ca\/wp-content\/uploads\/2018\/01\/Markham-Street-James-Weyman.png\" alt=\"Markham Street - James Weyman\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 2\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/stage.rdvcanada.ca\/wp-content\/uploads\/2018\/01\/Ontario-Creates-Meet-the-Docs-2024.png\" alt=\"Ontario Creates - Meet the Docs 2024\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d79761d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d79761d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-8e43b3a\" data-id=\"8e43b3a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c41bb53 elementor-widget elementor-widget-heading\" data-id=\"c41bb53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Dancehall Queen \u2013 Long m\u00e9trage<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-585b902 elementor-widget elementor-widget-text-editor\" data-id=\"585b902\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Marcelle Edwards, Productions From Mars (Ontario)<\/strong><\/p><p>Huit femmes venues du monde entier s\u2019affrontent en dansant pour participer \u00e0 la comp\u00e9tition internationale Dancehall Queen en Jama\u00efque et tenter de gagner la notori\u00e9t\u00e9, le prix dot\u00e9 et la couronne. En cours de route, le public sera immerg\u00e9 dans la culture dancehall jama\u00efcaine, rencontrera les artistes qui produisent la musique, les cr\u00e9ateurs des chor\u00e9graphies et les influenceurs de mode qui leur inspirent des looks audacieux, sexy et captivants.<\/p><p><em>La participation de la productrice est soutenue par le Bureau de l\u2019\u00e9cran des Noirs.<\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-28c8eb6\" data-id=\"28c8eb6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-61622e2 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"61622e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrousel d\u2019images\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 2\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/stage.rdvcanada.ca\/wp-content\/uploads\/2018\/01\/Productionz-from-Mars-Marcelle-Edwards.png\" alt=\"Productionz from Mars - Marcelle Edwards\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 2\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/stage.rdvcanada.ca\/wp-content\/uploads\/2018\/01\/BSO-Meet-the-Docs-2024.png\" alt=\"BSO - Meet the Docs 2024\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-517dfaa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"517dfaa\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-f504d9d\" data-id=\"f504d9d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bc9f663 elementor-widget elementor-widget-heading\" data-id=\"bc9f663\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Ancient Baby Beasts \u2013 \u00e9mission unique<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9def15a elementor-widget elementor-widget-text-editor\" data-id=\"9def15a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/stage.rdvcanada.ca\/fr\/creer-avec-le-canada\/trouver-des-partenaires-creatifs\/producteurs\/ari-cohen\/\"><strong>Ari A. Cohen<\/strong><\/a><strong>, Rotating Planet Productions Inc. (<b>Qu\u00e9bec<\/b>)<\/strong><\/p><p>Pendant des si\u00e8cles, il y a eu un pr\u00e9jug\u00e9 selon lequel plus c\u2019est gros, mieux c\u2019est ; chaque mus\u00e9e se vantant d\u2019avoir le plus gros squelette qui existe. Mais aujourd\u2019hui, gr\u00e2ce \u00e0 une technologie de pointe, nous nous tournons vers les plus jeunes et puissants de ces g\u00e9ants \u2013 les tout-petits et les adolescents des dinosaures et des mammif\u00e8res pr\u00e9historiques mettant en lumi\u00e8re leurs petites vies fascinantes.<\/p><p><em>La participation du producteur est soutenue par Qu\u00e9bec cr\u00e9atif, Sodec.<\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c2ddd9c\" data-id=\"c2ddd9c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d8f11d0 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"d8f11d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrousel d\u2019images\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 2\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/stage.rdvcanada.ca\/wp-content\/uploads\/2018\/01\/Rotating-Planet-Ari-Ari-A.-Cohen.png\" alt=\"Rotating Planet - Ari - Ari A. Cohen\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 2\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/stage.rdvcanada.ca\/wp-content\/uploads\/2018\/01\/Quebec-Creates-FR-Meet-the-Docs-2024.png\" alt=\"Quebec Creates - FR - Meet the Docs 2024\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0f46a40 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0f46a40\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-5d573bb\" data-id=\"5d573bb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-318666c elementor-widget elementor-widget-heading\" data-id=\"318666c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Mountain Sisters \u2013  Long m\u00e9trage<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf7f474 elementor-widget elementor-widget-text-editor\" data-id=\"cf7f474\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong><a href=\"https:\/\/stage.rdvcanada.ca\/fr\/creer-avec-le-canada\/trouver-des-partenaires-creatifs\/producteurs\/carmen-forsberg\/\">Carmen Forsberg<\/a>, Silverlight Entertainment Inc. (<b>Colombie-Britannique<\/b>)<\/strong><\/p><p>Cinq alpinistes \u00e9lev\u00e9es dans des villes recul\u00e9es des Andes p\u00e9ruviennes ont pour objectif de gravir la montagne Manaslu, huiti\u00e8me plus haut sommet du monde, sans oxyg\u00e8ne suppl\u00e9mentaire ni porteurs. \u00c0 leur t\u00eate se trouve Flor Cuenca, une force de la nature et un nom de plus en plus connu sur les sommets \u00ab 8K \u00bb du monde. Ensemble, elles pr\u00e9voient de transporter 100 kg de d\u00e9chets depuis les camps de base sup\u00e9rieurs, plaidant ainsi en faveur de la protection de l\u2019environnement et remettant en question les normes de genre en alpinisme. Leur mission n&#8217;est pas seulement un effort physique mais un appel \u00e0 l&#8217;action pour la responsabilit\u00e9 \u00e9cologique et l&#8217;\u00e9galit\u00e9 des sexes dans les sports de haute altitude.<\/p><p><em>La participation de la productrice est soutenue par Creative BC.<\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-136979d\" data-id=\"136979d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d8bfd00 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"d8bfd00\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrousel d\u2019images\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 2\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/stage.rdvcanada.ca\/wp-content\/uploads\/2018\/01\/Silverlight-Carmen-Forsberg.png\" alt=\"Silverlight - Carmen Forsberg\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 2\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/stage.rdvcanada.ca\/wp-content\/uploads\/2018\/01\/Creative-BC-Meet-the-Docs-Logo-1.png\" alt=\"Creative BC - Meet the Docs Logo\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-93b37c2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"93b37c2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-29a6c05\" data-id=\"29a6c05\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c63fc1f elementor-widget elementor-widget-spacer\" data-id=\"c63fc1f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6124cf5 elementor-widget elementor-widget-text-editor\" data-id=\"6124cf5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Ayant pour but d\u2019aider les productrices et les producteurs canadiens de diff\u00e9rents genres \u00e0 accro\u00eetre leur pr\u00e9sence sur les march\u00e9s \u00e9trangers et \u00e0 faire affaire avec des partenaires internationaux, l\u2019initiative RDVCANADA a \u00e9t\u00e9 cr\u00e9\u00e9e par T\u00e9l\u00e9film Canada et le Service des d\u00e9l\u00e9gu\u00e9s commerciaux en 2020. Il s\u2019agit de la deuxi\u00e8me it\u00e9ration ax\u00e9e sur le documentaire. Pour en savoir plus sur la cohorte 2021, cliquez\u00a0<a href=\"https:\/\/stage.rdvcanada.ca\/fr\/evenements\/voici-votre-cohorte-a-la-rencontre-des-docs-2021\/\">ici<\/a>.<\/strong><\/p><p><strong> Comme pour les \u00e9ditions pr\u00e9c\u00e9dentes de RDVCANADA \u2013 qui portaient sur les s\u00e9ries, les animations et les documentaires \u2013 les productrices et producteurs participant \u00e0 RDVCANADA | Docs 2024 proviennent de partout au Canada.\u00a0<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Sunny Side of the Doc, les voici! Dans le cadre de notre initiative de mentorat RDVCANADA, notre deuxi\u00e8me cohorte de productrices et de producteurs de documentaires est pr\u00eate \u00e0 s\u2019attaquer au march\u00e9 mondial pour trouver leurs prochains partenaires d\u2019affaires internationaux. Arm\u00e9s de leurs projets documentaires en d\u00e9veloppement, les sept productrices et producteurs s\u00e9lectionn\u00e9s pour RDVCANADA&#8230;<\/p>\n","protected":false},"author":1203,"featured_media":90181,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[335,334],"tags":[],"class_list":["post-90194","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-incontournables","category-succes","posts_festivals-sunny-side-of-the-doc-2024","posts_festivals-sunny-side-of-the-doc-2024-2"],"acf":[],"_links":{"self":[{"href":"https:\/\/stage.rdvcanada.ca\/fr\/wp-json\/wp\/v2\/posts\/90194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stage.rdvcanada.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stage.rdvcanada.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stage.rdvcanada.ca\/fr\/wp-json\/wp\/v2\/users\/1203"}],"replies":[{"embeddable":true,"href":"https:\/\/stage.rdvcanada.ca\/fr\/wp-json\/wp\/v2\/comments?post=90194"}],"version-history":[{"count":10,"href":"https:\/\/stage.rdvcanada.ca\/fr\/wp-json\/wp\/v2\/posts\/90194\/revisions"}],"predecessor-version":[{"id":91070,"href":"https:\/\/stage.rdvcanada.ca\/fr\/wp-json\/wp\/v2\/posts\/90194\/revisions\/91070"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stage.rdvcanada.ca\/fr\/wp-json\/wp\/v2\/media\/90181"}],"wp:attachment":[{"href":"https:\/\/stage.rdvcanada.ca\/fr\/wp-json\/wp\/v2\/media?parent=90194"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stage.rdvcanada.ca\/fr\/wp-json\/wp\/v2\/categories?post=90194"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stage.rdvcanada.ca\/fr\/wp-json\/wp\/v2\/tags?post=90194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}